{"id":1337985,"date":"2026-09-02T03:10:35","date_gmt":"2026-09-02T01:10:35","guid":{"rendered":"https:\/\/www.stewe.de\/helfer-reinigung-brunohl-gummersbach-8970"},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-29T22:00:00","slug":"helfer-reinigung-brunohl-gummersbach-8970","status":"publish","type":"stellenanzeige","link":"https:\/\/www.stewe.de\/en\/stellenanzeige\/helfer-reinigung-brunohl-gummersbach-8970","title":{"rendered":"Helfer &#8211; Reinigung  Brunohl- Gummersbach [8970]"},"content":{"rendered":"<h2>Freuen Sie sich auf<\/h2>\n<ul>\n<li>Einen sicheren Job<\/li>\n<li>Zuverl\u00e4ssige Bezahlung nach Tariflohn<\/li>\n<li>Flexibilit\u00e4t in der Einteilung der Stunden<\/li>\n<li>Gute Einarbeitung durch erfahrene Kollegen<\/li>\n<li>Einen festen Objektleiter (m\/w\/d) als Ansprechpartner<\/li>\n<\/ul>\n<figure class=\"wp-caption\"><\/figure>\n<h2>Ihr neuer Job<\/h2>\n<p><span style=\"background-color: rgb(255, 255, 255); color: rgb(12, 12, 11);\">\u2728Wir suchen ab den 01.09.2026 eine freundliche und zuverl\u00e4ssige Reinigungskraft f\u00fcr ein Objekt in Brunohl auf Minijob Basis\u2728<\/span><\/p>\n<figure class=\"wp-caption\"><\/figure>\n<figure class=\"wp-caption\"><\/figure>\n<p><span style=\"background-color: rgb(255, 255, 255); color: rgb(12, 12, 11);\">\u23f0Ihre Arbeitszeiten sind Montags bis Freitags ab 15:00 Uhr f\u00fcr 8,25 Stunden pro Woche.<\/span><\/p>\n<figure class=\"wp-caption\"><\/figure>\n<p><span style=\"background-color: rgb(255, 255, 255); color: rgb(12, 12, 11);\">Schl\u00fcsselstelle<\/span><\/p>\n<h2>Ihr Profil<\/h2>\n<ul>\n<li>Zuverl\u00e4ssig<\/li>\n<li>Haben erste Erfahrungen in der Reinigung von Objekten<\/li>\n<li>W\u00fcnschenswert ist ein F\u00fchrerschein Klasse B<\/li>\n<li>Mindestens Grundkenntnisse in Deutsch<\/li>\n<li>Mindestens 16 Jahre alt und 10 abgeschlossene Schuljahre<\/li>\n<\/ul>\n<figure class=\"wp-caption\"><\/figure>\n<h2>Wir freuen uns auf Sie!<\/h2>\n<p>Bewerben Sie sich heute \u2013 gerne auch telefonisch \u2013 bei uns!<\/p>\n<p>Wir freuen uns auf Sie!<\/p>\n<h2>\u00dcber stewe Dienstleistungen<\/h2>\n<p> <span style=\"background-color: rgb(247, 250, 252); color: rgb(33, 37, 41);\">Wir sind die stewe Dienstleistungen GmbH und stehen unseren Kunden seit mehr als 30 Jahren zuverl\u00e4ssig zur Seite. Seit Anfang des Jahres sind wir \u00fcber 1.600 Mitarbeitende bei mehr als 600 Kunden und suchen dringend Verst\u00e4rkung im Bereich der Unterhaltsreinigung. Werden Sie ein Teil von uns!<\/span><\/p>\n<p><span style=\"background-color: rgb(247, 250, 252); color: rgb(33, 37, 41);\">Unser Motto ist: &quot;Qualit\u00e4t ist kein Zustand, sondern ein Prozess.&quot; Wir arbeiten stetig daran, dass wir immer besser werden und begleiten unsere Kunden in dem Prozess der Sauberkeit ma\u00dfgeblich. Das Ziel ist eine kosteneffiziente Reinigung nach modernsten Ma\u00dfst\u00e4ben und unter bestm\u00f6glichen Bedingungen.<\/span><\/p><\/p>\n","protected":false},"author":7,"template":"","class_list":["post-1337985","stellenanzeige","type-stellenanzeige","status-publish","hentry","stellenanzeige_kategorie-allgemeine-dienstleistung","art_der_anstellung-geringfuegig-beschaeftigt","type_stellenanzeige-mini-job-geringfuegige-kurzfristige","firma_stellenanzeige-talent-360"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.stewe.de\/en\/wp-json\/wp\/v2\/stellenanzeigen\/1337985","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stewe.de\/en\/wp-json\/wp\/v2\/stellenanzeigen"}],"about":[{"href":"https:\/\/www.stewe.de\/en\/wp-json\/wp\/v2\/types\/stellenanzeige"}],"author":[{"embeddable":true,"href":"https:\/\/www.stewe.de\/en\/wp-json\/wp\/v2\/users\/7"}],"wp:attachment":[{"href":"https:\/\/www.stewe.de\/en\/wp-json\/wp\/v2\/media?parent=1337985"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}