{"id":1337512,"date":"2026-09-02T03:10:21","date_gmt":"2026-09-02T01:10:21","guid":{"rendered":"https:\/\/www.stewe.de\/staplerfahrer-ab-1608e-andernach-7829"},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-29T22:00:00","slug":"staplerfahrer-ab-1608e-andernach-7829","status":"publish","type":"stellenanzeige","link":"https:\/\/www.stewe.de\/en\/stellenanzeige\/staplerfahrer-ab-1608e-andernach-7829","title":{"rendered":"Staplerfahrer  ab 16,08\u20ac- Andernach [7829]"},"content":{"rendered":"<figure class=\"wp-caption\"><\/figure>\n<p><strong>Wir suchen DICH! <\/strong><\/p>\n<figure class=\"wp-caption\"><\/figure>\n<p><strong>Bewirb dich<\/strong> jetzt als <strong>Staplerfahrer (m\/w\/d)<\/strong> \/ <strong>Gabelstaplerfahrer (m\/w\/d)<\/strong> und werde Teil des Teams.<\/p>\n<figure class=\"wp-caption\"><\/figure>\n<p>Ziel ist die <strong>\u00dcbernahme<\/strong> in eine <strong>Festanstellung!<\/strong><\/p>\n<h2>Freu dich auf<\/h2>\n<ul>\n<li>Einen <strong>unbefristeten Arbeitsvertrag <\/strong><\/li>\n<li><strong>P\u00fcnktliche Bezahlung <\/strong>+ tarifliche <strong>Zuschl\u00e4ge f\u00fcr \u00dcberstunden <\/strong><\/li>\n<li><strong>30 Tage Urlaubanspruch <\/strong>je nach Betriebszugeh\u00f6rigkeit<\/li>\n<li><strong>Weihnachts- und Urlaubsgeld<\/strong><\/li>\n<li><strong>Abschlagszahlungen<\/strong> zum 1. eines Monats m\u00f6glich<\/li>\n<li><strong>300-Euro-Pr\u00e4mie<\/strong> bei Gewinnung von neuen Kollegen\/innen<\/li>\n<li><strong>Fahrdienst<\/strong><\/li>\n<li>Eine <strong>hohe \u00dcbernahmechance<\/strong> in unseren Kundenbetrieb<\/li>\n<\/ul>\n<h2>Deine Aufgaben<\/h2>\n<ul>\n<li>Innerbetrieblicher Warentransport<\/li>\n<li>Einlagern der Ware im vorgesehenen Lagerbereich<\/li>\n<li>Be- und Entladen von LKW\u00b4s<\/li>\n<\/ul>\n<h2>Dein Profil<\/h2>\n<ul>\n<li>Erfahrung und Kenntnisse im Umgang mit Gabelstaplern<\/li>\n<li>Gabelstaplerschein<\/li>\n<li>Sorgf\u00e4ltige und genaue Arbeitsweise<\/li>\n<\/ul>\n<h2>Wir freuen uns auf Dich!<\/h2>\n<p>Du bist der perfekte Kandidat? Dann klicke auf &quot;jetzt bewerben&quot; und wir werden Dich so schnell wie m\u00f6glich kontaktieren.<\/p>\n<h2>\u00dcber stewe Personalservice<\/h2>\n<p><strong>stewe Personalservice<\/strong> ist seit 2004 eine etablierte Gr\u00f6\u00dfe im Bereich Personaldienstleistung und Personalvermittlung.<\/p>\n<p>In 10 Niederlassungen betreuen wir aktuell eine stetig wachsende Zahl an zufriedenen Mitarbeitern aller Generationen.<\/p>\n","protected":false},"author":7,"template":"","class_list":["post-1337512","stellenanzeige","type-stellenanzeige","status-publish","hentry","duration_stellenanzeige-unbefristete-beschaeftigung","art_der_anstellung-vollzeit","type_stellenanzeige-festanstellung-zeitarbeit","firma_stellenanzeige-talent-360"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.stewe.de\/en\/wp-json\/wp\/v2\/stellenanzeigen\/1337512","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stewe.de\/en\/wp-json\/wp\/v2\/stellenanzeigen"}],"about":[{"href":"https:\/\/www.stewe.de\/en\/wp-json\/wp\/v2\/types\/stellenanzeige"}],"author":[{"embeddable":true,"href":"https:\/\/www.stewe.de\/en\/wp-json\/wp\/v2\/users\/7"}],"wp:attachment":[{"href":"https:\/\/www.stewe.de\/en\/wp-json\/wp\/v2\/media?parent=1337512"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}