{"id":1337477,"date":"2026-09-02T03:10:20","date_gmt":"2026-09-02T01:10:20","guid":{"rendered":"https:\/\/www.stewe.de\/lkw-fahrer-herne-7704"},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-29T22:00:00","slug":"lkw-fahrer-herne-7704","status":"publish","type":"stellenanzeige","link":"https:\/\/www.stewe.de\/en\/stellenanzeige\/lkw-fahrer-herne-7704","title":{"rendered":"LKW-Fahrer &#8211; Herne [7704]"},"content":{"rendered":"<p><strong>Wir suchen DICH! <\/strong><\/p>\n<figure class=\"wp-caption\"><\/figure>\n<p><strong>Bewirb dich<\/strong> jetzt als <strong>LKW-Fahrer (m\/w\/d), Berufskraftfahrer (m\/w\/d) im Nahverkehr<\/strong> f\u00fcr unseren Kunden <strong>in Gelsenkirchen<\/strong> und werde Teil des Teams.<\/p>\n<figure class=\"wp-caption\"><\/figure>\n<p><strong>JEDER<\/strong> ist willkommen (<strong>Quereinsteiger, Berufseinsteiger und Berufserfahrene).<\/strong><\/p>\n<figure class=\"wp-caption\"><\/figure>\n<p>Ziel ist die <strong>\u00dcbernahme<\/strong> in eine <strong>Festanstellung!<\/strong><\/p>\n<h2>Freu Dich auf <\/h2>\n<ul>\n<li>Einen <strong>unbefristeten Arbeitsvertrag <\/strong><\/li>\n<li><strong>P\u00fcnktliche Bezahlung <\/strong>+ tarifliche <strong>Zuschl\u00e4ge f\u00fcr \u00dcberstunden <\/strong><\/li>\n<li><strong>30 Tage Urlaubanspruch <\/strong>je nach Betriebszugeh\u00f6rigkeit<\/li>\n<li><strong>Weihnachts- und Urlaubsgeld<\/strong><\/li>\n<li><strong>Abschlagszahlungen<\/strong> zum 1. eines Monats m\u00f6glich<\/li>\n<li><strong>300-Euro-Pr\u00e4mie<\/strong> bei Gewinnung von neuen Kollegen\/innen<\/li>\n<li><strong>1.000-Euro-Wechselpr\u00e4mie<\/strong><\/li>\n<li><strong>Fahrtkostenzuschuss <\/strong><\/li>\n<li>Eine <strong>hohe \u00dcbernahmechance<\/strong> in unseren Kundenbetrieb<\/li>\n<\/ul>\n<h2>Dein neuer Job<\/h2>\n<ul>\n<li><strong>Transportieren<\/strong> von G\u00fctern<\/li>\n<li><strong>Beladen und Entladen<\/strong> des LKWs<\/li>\n<li><strong>Einlagern und Auslagern <\/strong>der Ware <\/li>\n<li><strong>Kontrollieren des LKWs<\/strong> vor Touren<\/li>\n<li>M\u00f6glicherweise <strong>Staplerfahren<\/strong><\/li>\n<\/ul>\n<h2>Dein Profil <\/h2>\n<ul>\n<li><strong>F\u00fchrerscheinklasse <\/strong>mindestens <strong>C, CE<\/strong><\/li>\n<li><strong>G\u00fcltige Fahrerkarte<\/strong> erforderlich<\/li>\n<li><strong>Module erforderlich<\/strong><\/li>\n<li><strong>ADR Schein<\/strong> w\u00fcnschenswert<\/li>\n<li><strong>Staplerschein<\/strong> w\u00fcnschenswert<\/li>\n<\/ul>\n<h2>Wir freuen uns auf Dich!<\/h2>\n<p>Du bist der perfekte Kandidat? Dann klicke auf <strong>&quot;jetzt bewerben&quot;<\/strong> und wir werden Dich so schnell wie m\u00f6glich kontaktieren.<\/p>\n<p>Du m\u00f6chtest sofort eine Antwort und kannst es kaum abwarten?<\/p>\n<p>Dann einfach unter dieser Nummer anrufen oder einfach eine direkte Mail an uns senden und ergattere Dir heute noch einen Job!<\/p>\n<h2>\u00dcber stewe Personalservice<\/h2>\n<p><strong>stewe Personalservice<\/strong> ist seit 2004 eine etablierte Gr\u00f6\u00dfe im Bereich Personaldienstleistung und Personalvermittlung.<\/p>\n<p>In 10 Niederlassungen betreuen wir aktuell eine stetig wachsende Zahl an zufriedenen Mitarbeitern aller Generationen.<\/p>\n","protected":false},"author":7,"template":"","class_list":["post-1337477","stellenanzeige","type-stellenanzeige","status-publish","hentry","stellenanzeige_kategorie-transport-logistik","duration_stellenanzeige-unbefristete-beschaeftigung","art_der_anstellung-vollzeit","type_stellenanzeige-festanstellung-zeitarbeit","firma_stellenanzeige-talent-360"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.stewe.de\/en\/wp-json\/wp\/v2\/stellenanzeigen\/1337477","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stewe.de\/en\/wp-json\/wp\/v2\/stellenanzeigen"}],"about":[{"href":"https:\/\/www.stewe.de\/en\/wp-json\/wp\/v2\/types\/stellenanzeige"}],"author":[{"embeddable":true,"href":"https:\/\/www.stewe.de\/en\/wp-json\/wp\/v2\/users\/7"}],"wp:attachment":[{"href":"https:\/\/www.stewe.de\/en\/wp-json\/wp\/v2\/media?parent=1337477"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}