{"id":1271056,"date":"2026-07-15T03:10:37","date_gmt":"2026-07-15T01:10:37","guid":{"rendered":"https:\/\/www.stewe.de\/hr-business-partner-remagen-8715"},"modified":"-0001-11-30T00:00:00","modified_gmt":"-0001-11-29T22:00:00","slug":"hr-business-partner-remagen-8715","status":"publish","type":"stellenanzeige","link":"https:\/\/www.stewe.de\/en\/stellenanzeige\/hr-business-partner-remagen-8715","title":{"rendered":"HR Business Partner &#8211; Remagen [8715]"},"content":{"rendered":"<figure class=\"wp-caption\"><\/figure>\n<p> <strong>Wir suchen SIE! <\/strong><\/p>\n<figure class=\"wp-caption\"><\/figure>\n<p><strong>Bewerben Sie sich<\/strong> jetzt als <strong>HR Business Partner <\/strong>(m\/w\/d) \/ <strong>Personalreferent <\/strong>(m\/w\/d) und werden Sie Teil des Teams!<\/p>\n<figure class=\"wp-caption\"><\/figure>\n<figure class=\"wp-caption\"><\/figure>\n<\/p>\n<h2>Freuen Sie sich auf<\/h2>\n<ul>\n<li>Einen <strong>unbefristeten Arbeitsvertrag <\/strong><\/li>\n<li><strong>30 Tage Urlaubanspruch <\/strong>je nach Betriebszugeh\u00f6rigkeit<\/li>\n<li><strong>Weihnachts- und Urlaubsgeld<\/strong><\/li>\n<li><strong>Abschlagszahlungen<\/strong> zum 1. eines Monats m\u00f6glich<\/li>\n<li><strong>300-Euro-Pr\u00e4mie<\/strong> bei Gewinnung von neuen Kollegen\/innen<\/li>\n<li><strong>Fahrtkostenzuschuss <\/strong><\/li>\n<\/ul>\n<h2>Ihr neuer Job<\/h2>\n<ul>\n<li><strong>Strategische Beratung<\/strong> und <strong>Unterst\u00fctzung <\/strong>der F\u00fchrungskr\u00e4fte in allen HR-relevanten Themen<\/li>\n<li>Verantwortung f\u00fcr <strong>Recruiting<\/strong>, <strong>Personalplanung <\/strong>sowie professionelle <strong>Onboarding-Prozesse<\/strong><\/li>\n<li><strong>Weiterentwicklung <\/strong>von <strong>Performance-Management<\/strong>-, <strong>Talent<\/strong>&#8211; und <strong>Entwicklungsprogrammen<\/strong><\/li>\n<li>Sicherstellung der <strong>Einhaltung arbeitsrechtlicher<\/strong> <strong>Compliance<\/strong>&#8211; und <strong>HR<\/strong>&#8211;<strong>Governance<\/strong>&#8211;<strong>Vorgaben<\/strong><\/li>\n<li><strong>F\u00f6rderung <\/strong>von <strong>Mitarbeiterengagement<\/strong>, <strong>Kommunikation <\/strong>sowie einer <strong>positiven Unternehmenskultur<\/strong><\/li>\n<li>Enge <strong>Zusammenarbeit <\/strong>mit den Bereichen <strong>Produktion<\/strong>, <strong>Supply Chain<\/strong>, <strong>Finance<\/strong>, <strong>EHS <\/strong>und weiteren internationalen Schnittstellen<\/li>\n<li><strong>Durchf\u00fchrung <\/strong>von <strong>Gehaltsbenchmark-Analysen<\/strong> f\u00fcr alle Positionen  <\/li>\n<\/ul>\n<h2>Ihr Profil<\/h2>\n<ul>\n<li><strong>Abgeschlossenes Studium<\/strong> im Bereich <strong>Human Resources<\/strong>, <strong>Wirtschaft<\/strong>, <strong>Betriebswirtschaft <\/strong>oder vergleichbare Qualifikation\/Berufserfahrung<\/li>\n<li><strong>Fundierte Kenntnisse<\/strong> des <strong>deutschen Arbeitsrechts<\/strong><\/li>\n<li>Sehr gute <strong>schriftliche <\/strong>und <strong>m\u00fcndliche Kommunikationsf\u00e4higkeiten<\/strong><\/li>\n<li>Sicherer Umgang mit <strong>MS Office  <\/strong><\/li>\n<li>Sehr gute <strong>Englischkenntnisse<\/strong><\/li>\n<li><strong>Verhandlungsgeschick<\/strong><\/li>\n<li><strong>Integrit\u00e4t <\/strong>und <strong>Vertrauensw\u00fcrdigkeit<\/strong><\/li>\n<\/ul>\n<h2>Wir freuen uns auf Sie!<\/h2>\n<p><span style=\"color: black;\">F\u00fchlen Sie sich angesprochen? Gerne k\u00f6nnen Sie sich auf diese Position bewerben oder bei Fragen Kontakt aufnehmen!<\/span><\/p>\n<\/p>\n<h2>\u00dcber stewe Personalservice<\/h2>\n<p><strong>stewe Personalservice<\/strong> ist seit 2004 eine etablierte Gr\u00f6\u00dfe im Bereich Personaldienstleistung und Personalvermittlung.<\/p>\n<p>In 10 Niederlassungen betreuen wir aktuell eine stetig wachsende Zahl an zufriedenen Mitarbeitern aller Generationen.<\/p>\n","protected":false},"author":7,"template":"","class_list":["post-1271056","stellenanzeige","type-stellenanzeige","status-publish","hentry","stellenanzeige_kategorie-elektronik","duration_stellenanzeige-unbefristete-beschaeftigung","art_der_anstellung-vollzeit","type_stellenanzeige-festanstellung-zeitarbeit","firma_stellenanzeige-talent-360"],"acf":[],"_links":{"self":[{"href":"https:\/\/www.stewe.de\/en\/wp-json\/wp\/v2\/stellenanzeigen\/1271056","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.stewe.de\/en\/wp-json\/wp\/v2\/stellenanzeigen"}],"about":[{"href":"https:\/\/www.stewe.de\/en\/wp-json\/wp\/v2\/types\/stellenanzeige"}],"author":[{"embeddable":true,"href":"https:\/\/www.stewe.de\/en\/wp-json\/wp\/v2\/users\/7"}],"wp:attachment":[{"href":"https:\/\/www.stewe.de\/en\/wp-json\/wp\/v2\/media?parent=1271056"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}